{"id":333179,"date":"2024-07-18T16:49:05","date_gmt":"2024-07-18T14:49:05","guid":{"rendered":"https:\/\/lalmachine.com\/?post_type=product&#038;p=333179"},"modified":"2024-12-05T22:05:26","modified_gmt":"2024-12-05T21:05:26","slug":"etagere-vintage-4","status":"publish","type":"product","link":"https:\/\/lalmachine.com\/de\/shop\/meubler\/meuble-de-rangement\/etagere-vintage-4\/","title":{"rendered":"\u00c9tag\u00e8re vintage"},"content":{"rendered":"<ul class=\"wpuf_customs\"><li style=\"list-style-type:none;\"><label>Autres photos:<\/label> <a href=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7529-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"72\" height=\"96\" src=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7529-scaled.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a> <a href=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7527-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"72\" height=\"96\" src=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7527-scaled.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a> <a href=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7528.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"72\" height=\"96\" src=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7528.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a> <a href=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7530-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"72\" height=\"96\" src=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7530-scaled.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a> <a href=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7531-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"72\" height=\"96\" src=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7531-scaled.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a> <a href=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7532-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"72\" height=\"96\" src=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7532-scaled.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a> <a href=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7533-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"72\" height=\"96\" src=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7533-scaled.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a> <a href=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7534-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"72\" height=\"96\" src=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7534-scaled.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a> <a href=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7536-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"72\" height=\"96\" src=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7536-scaled.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a> <a href=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7537.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"78\" height=\"96\" src=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7537.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a> <a href=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7538-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"72\" height=\"96\" src=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7538-scaled.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a> <a href=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7539-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"72\" height=\"96\" src=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7539-scaled.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a> <a href=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7540-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"72\" height=\"96\" src=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7540-scaled.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a> <a href=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7542-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"72\" height=\"96\" src=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7542-scaled.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a> <a href=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7541-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"72\" height=\"96\" src=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7541-scaled.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a> <\/li>        <li class=\"wpuf-field-data wpuf-field-data-numeric_text_field\">\n                            <label>Prix:<\/label>\n                        520        <\/li>\n                <li class=\"wpuf-field-data wpuf-field-data-numeric_text_field\">\n                            <label>Hauteur (cm):<\/label>\n                        123        <\/li>\n                <li class=\"wpuf-field-data wpuf-field-data-numeric_text_field\">\n                            <label>Largeur (cm):<\/label>\n                        120        <\/li>\n                <li class=\"wpuf-field-data wpuf-field-data-numeric_text_field\">\n                            <label>Profondeur (cm):<\/label>\n                        40        <\/li>\n        <\/ul>","protected":false},"excerpt":{"rendered":"<p>\u00c9tag\u00e8re vintage avec une porte coulissante.<br \/>\nEn bon \u00e9tat hormis quelques petites traces, peu visibles.<br \/>\n\u00c0 venir chercher \u00e0 Satigny (1242) ou livraison possible Geneve\/Vaud (devis sur demande).<\/p>","protected":false},"featured_media":333193,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[83,47],"product_tag":[],"proximite":[180],"class_list":{"0":"post-333179","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-meuble-de-rangement","7":"product_cat-meubler","8":"pa_couleur-bois","9":"pa_etat-bon-etat","10":"pa_materiau-bois","11":"pa_style-vintage","12":"proximite-geneve","14":"first","15":"outofstock","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9tag\u00e8re vintage | lalmachine.com, mobilier et objets d\u00e9co vintage et design<\/title>\n<meta name=\"description\" content=\"\u00c9tag\u00e8re vintage avec une porte coulissante.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lalmachine.com\/de\/shop\/meubler\/meuble-de-rangement\/etagere-vintage-4\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9tag\u00e8re vintage | lalmachine.com, mobilier et objets d\u00e9co vintage et design\" \/>\n<meta property=\"og:description\" content=\"\u00c9tag\u00e8re vintage avec une porte coulissante.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lalmachine.com\/de\/shop\/meubler\/meuble-de-rangement\/etagere-vintage-4\/\" \/>\n<meta property=\"og:site_name\" content=\"lalmachine.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/lalmachine\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-05T21:05:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7529-scaled_clipped_rev_1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2019\" \/>\n\t<meta property=\"og:image:height\" content=\"2020\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lalmachine.com\\\/shop\\\/meubler\\\/meuble-de-rangement\\\/etagere-vintage-4\\\/\",\"url\":\"https:\\\/\\\/lalmachine.com\\\/shop\\\/meubler\\\/meuble-de-rangement\\\/etagere-vintage-4\\\/\",\"name\":\"\u00c9tag\u00e8re vintage | lalmachine.com, mobilier et objets d\u00e9co vintage et design\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lalmachine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lalmachine.com\\\/shop\\\/meubler\\\/meuble-de-rangement\\\/etagere-vintage-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lalmachine.com\\\/shop\\\/meubler\\\/meuble-de-rangement\\\/etagere-vintage-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lalmachine.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/IMG_7529-scaled_clipped_rev_1.jpeg\",\"datePublished\":\"2024-07-18T14:49:05+00:00\",\"dateModified\":\"2024-12-05T21:05:26+00:00\",\"description\":\"\u00c9tag\u00e8re vintage avec une porte coulissante.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lalmachine.com\\\/shop\\\/meubler\\\/meuble-de-rangement\\\/etagere-vintage-4\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lalmachine.com\\\/shop\\\/meubler\\\/meuble-de-rangement\\\/etagere-vintage-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/lalmachine.com\\\/shop\\\/meubler\\\/meuble-de-rangement\\\/etagere-vintage-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lalmachine.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/IMG_7529-scaled_clipped_rev_1.jpeg\",\"contentUrl\":\"https:\\\/\\\/lalmachine.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/IMG_7529-scaled_clipped_rev_1.jpeg\",\"width\":2019,\"height\":2020,\"caption\":\"\u00c9tag\u00e8re vintage\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lalmachine.com\\\/shop\\\/meubler\\\/meuble-de-rangement\\\/etagere-vintage-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lalmachine.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/lalmachine.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c9tag\u00e8re vintage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lalmachine.com\\\/#website\",\"url\":\"https:\\\/\\\/lalmachine.com\\\/\",\"name\":\"lalmachine.com\",\"description\":\"Brocante en ligne Suisse | Mobilier et objets d\u00e9co vintage et design\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lalmachine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9tag\u00e8re vintage | lalmachine.com, mobilier et objets d\u00e9co vintage et design","description":"\u00c9tag\u00e8re vintage avec une porte coulissante.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lalmachine.com\/de\/shop\/meubler\/meuble-de-rangement\/etagere-vintage-4\/","og_locale":"de_DE","og_type":"article","og_title":"\u00c9tag\u00e8re vintage | lalmachine.com, mobilier et objets d\u00e9co vintage et design","og_description":"\u00c9tag\u00e8re vintage avec une porte coulissante.","og_url":"https:\/\/lalmachine.com\/de\/shop\/meubler\/meuble-de-rangement\/etagere-vintage-4\/","og_site_name":"lalmachine.com","article_publisher":"https:\/\/facebook.com\/lalmachine","article_modified_time":"2024-12-05T21:05:26+00:00","og_image":[{"width":2019,"height":2020,"url":"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7529-scaled_clipped_rev_1.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lalmachine.com\/shop\/meubler\/meuble-de-rangement\/etagere-vintage-4\/","url":"https:\/\/lalmachine.com\/shop\/meubler\/meuble-de-rangement\/etagere-vintage-4\/","name":"\u00c9tag\u00e8re vintage | lalmachine.com, mobilier et objets d\u00e9co vintage et design","isPartOf":{"@id":"https:\/\/lalmachine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lalmachine.com\/shop\/meubler\/meuble-de-rangement\/etagere-vintage-4\/#primaryimage"},"image":{"@id":"https:\/\/lalmachine.com\/shop\/meubler\/meuble-de-rangement\/etagere-vintage-4\/#primaryimage"},"thumbnailUrl":"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7529-scaled_clipped_rev_1.jpeg","datePublished":"2024-07-18T14:49:05+00:00","dateModified":"2024-12-05T21:05:26+00:00","description":"\u00c9tag\u00e8re vintage avec une porte coulissante.","breadcrumb":{"@id":"https:\/\/lalmachine.com\/shop\/meubler\/meuble-de-rangement\/etagere-vintage-4\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lalmachine.com\/shop\/meubler\/meuble-de-rangement\/etagere-vintage-4\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/lalmachine.com\/shop\/meubler\/meuble-de-rangement\/etagere-vintage-4\/#primaryimage","url":"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7529-scaled_clipped_rev_1.jpeg","contentUrl":"https:\/\/lalmachine.com\/wp-content\/uploads\/2024\/07\/IMG_7529-scaled_clipped_rev_1.jpeg","width":2019,"height":2020,"caption":"\u00c9tag\u00e8re vintage"},{"@type":"BreadcrumbList","@id":"https:\/\/lalmachine.com\/shop\/meubler\/meuble-de-rangement\/etagere-vintage-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lalmachine.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/lalmachine.com\/shop\/"},{"@type":"ListItem","position":3,"name":"\u00c9tag\u00e8re vintage"}]},{"@type":"WebSite","@id":"https:\/\/lalmachine.com\/#website","url":"https:\/\/lalmachine.com\/","name":"lalmachine.com","description":"Brocante en ligne Suisse | Mobilier et objets d\u00e9co vintage et design","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lalmachine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/lalmachine.com\/de\/wp-json\/wp\/v2\/product\/333179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lalmachine.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lalmachine.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lalmachine.com\/de\/wp-json\/wp\/v2\/media\/333193"}],"wp:attachment":[{"href":"https:\/\/lalmachine.com\/de\/wp-json\/wp\/v2\/media?parent=333179"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lalmachine.com\/de\/wp-json\/wp\/v2\/product_brand?post=333179"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lalmachine.com\/de\/wp-json\/wp\/v2\/product_cat?post=333179"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lalmachine.com\/de\/wp-json\/wp\/v2\/product_tag?post=333179"},{"taxonomy":"proximite","embeddable":true,"href":"https:\/\/lalmachine.com\/de\/wp-json\/wp\/v2\/proximite?post=333179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}